{"id":7580,"date":"2023-10-19T09:36:56","date_gmt":"2023-10-19T09:36:56","guid":{"rendered":"https:\/\/mobilbox.hu\/en\/?page_id=7580"},"modified":"2023-10-19T09:44:14","modified_gmt":"2023-10-19T09:44:14","slug":"container-camera-reflector-holder","status":"publish","type":"page","link":"https:\/\/mobilbox.hu\/en\/container-camera-reflector-holder\/","title":{"rendered":"Container camera\/ reflector holder"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-7580\" data-postid=\"7580\" class=\"themify_builder_content themify_builder_content-7580 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_puit331 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_5dx0332 first\">\n                            <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_2 tb_8ihn758\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column col4-2 tb_551n758 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_evol323   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p dir=\"ltr\" data-placeholder=\"Ford\u00edt\u00e1s\" data-ved=\"2ahUKEwjms8Hlz4GCAxXZh_0HHeXfC9YQ3ewLegQIBhAQ\">\/art. number: K1963\/<\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Ford\u00edt\u00e1s\" data-ved=\"2ahUKEwjms8Hlz4GCAxXZh_0HHeXfC9YQ3ewLegQIBhAQ\"><span class=\"Y2IQFc\" lang=\"en\">Support stand for attaching security cameras and lighting fixtures to the container. It can be easily installed in a container corner with a screw connection.<\/span><\/p>\n<hr>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Ford\u00edt\u00e1s\" data-ved=\"2ahUKEwjms8Hlz4GCAxXZh_0HHeXfC9YQ3ewLegQIBhAQ\"><span class=\"Y2IQFc\" lang=\"en\">Height: 1.5 m <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Ford\u00edt\u00e1s\" data-ved=\"2ahUKEwjms8Hlz4GCAxXZh_0HHeXfC9YQ3ewLegQIBhAQ\"><span class=\"Y2IQFc\" lang=\"en\">Material: galvanized steel, weather resistant<\/span><\/p>\n<hr>\n<p dir=\"ltr\" data-placeholder=\"Ford\u00edt\u00e1s\" data-ved=\"2ahUKEwjms8Hlz4GCAxXZh_0HHeXfC9YQ3ewLegQIBhAQ\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column sub_column col4-2 tb_b4t0758 last\">\n                    <!-- module gallery -->\n<div  class=\"module gallery module-gallery tb_dwbo952 layout-grid  \" data-lazy=\"1\">\n    <div class=\"module-gallery-grid\" style=\"--gald:2;--galt:2;--galm:2\">\n            <dl class=\"gallery-item\">\n            <dt class=\"gallery-icon\">\n            <a data-title=\"\" title=\"\" href=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder-1.jpg\" data-rel=\"tb_dwbo952\" class=\"themify_lightbox\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder-1-531x1024-200x400.jpg\" width=\"200\" height=\"400\" class=\"wp-post-image wp-image-7583\" title=\"camera-holder-1\" alt=\"camera-holder-1\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder-1-531x1024-200x400.jpg 200w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder-1-531x1024-100x200.jpg 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>            <\/dt>\n                    <\/dl>\n            <dl class=\"gallery-item\">\n            <dt class=\"gallery-icon\">\n            <a data-title=\"\" title=\"\" href=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder.jpg\" data-rel=\"tb_dwbo952\" class=\"themify_lightbox\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder-200x400.jpg\" width=\"200\" height=\"400\" class=\"wp-post-image wp-image-7584\" title=\"camera-holder\" alt=\"camera-holder\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder-200x400.jpg 200w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2023\/10\/camera-holder-100x200.jpg 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>            <\/dt>\n                    <\/dl>\n    <\/div>\n<\/div>\n<!-- \/module gallery -->        <\/div>\n                    <\/div>\n                <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_ltfz180 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_4f9i180 first\">\n                    <!-- module template_part -->\n<div  class=\"module module-layout-part tb_zv8o762 \">\n    <div class=\"tb_layout_part_wrap tf_w\"><!--themify_builder_content-->\n    <div  class=\"themify_builder_content themify_builder_content-3434 themify_builder not_editable_builder in_the_loop\" data-postid=\"3434\">\n                        <div  data-css_id=\"7885e66\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_7885e66 tf_w\">\n            <span  class=\"builder_row_cover tf_abs\" data-lazy=\"1\"><\/span>            <div class=\"row_inner col_align_top tb_col_count_3 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col4-1 tb_a5f2af4 first\">\n                            <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_6f6ac2e\">\n                    <!-- module fancy heading -->\n<div  class=\"module module-fancy-heading tb_cfaf205 \" data-lazy=\"1\">\n        <h2 class=\"fancy-heading tf_textc\">\n    <span class=\"main-head tf_block\">\n                    WRITE TO US            <\/span>\n\n    \n    <span class=\"sub-head tf_block tf_rel\">\n                                <\/span>\n    <\/h2>\n<\/div>\n<!-- \/module fancy heading -->\n<!-- module text -->\n<div  class=\"module module-text tb_8d9d061  repeat \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p style=\"text-align: center;\">For the container and accessory prices, please complete this inquiry form!<\/p>\n<p style=\"text-align: center;\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-7736\"><form id=\"wpforms-form-7736\" class=\"wpforms-validate wpforms-form\" data-formid=\"7736\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/7580?wpforms_form_id=7736\" data-token=\"f18296b1c5cca6684f6c5d7cf562b73a\" data-token-time=\"1788323313\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-7736-field_53-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-type=\"hidden\" data-field-id=\"53\"><input type=\"hidden\" id=\"wpforms-7736-field_53\" name=\"wpforms[fields][53]\" value=\"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/7580\"><\/div><div id=\"wpforms-7736-field_50-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"50\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_2\">Company name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-7736-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-7736-field_28-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_28\">Phone: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-7736-field_28\" class=\"wpforms-field-large wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][28]\" aria-label=\"Phone:\" required><\/div><div id=\"wpforms-7736-field_51-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"51\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_51\">Contact person name:<\/label><input type=\"text\" id=\"wpforms-7736-field_51\" class=\"wpforms-field-medium\" name=\"wpforms[fields][51]\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_19-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_19\">Postal code, city:<\/label><input type=\"text\" id=\"wpforms-7736-field_19\" class=\"wpforms-field-large\" name=\"wpforms[fields][19]\" ><\/div><div id=\"wpforms-7736-field_20-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_20\">Email:<\/label><input type=\"email\" id=\"wpforms-7736-field_20\" class=\"wpforms-field-large\" name=\"wpforms[fields][20]\" spellcheck=\"false\" ><\/div><div id=\"wpforms-7736-field_24-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_24\">Rental\/buy:<\/label><select id=\"wpforms-7736-field_24\" class=\"wpforms-field-large\" name=\"wpforms[fields][24]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Rental\/Buy<\/option><option value=\"I would like to rent\"  class=\"choice-1 depth-1\"  >I would like to rent<\/option><option value=\"I would like to buy\"  class=\"choice-2 depth-1\"  >I would like to buy<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_10-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"10\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_10\">Expected time period of rental:<\/label><input type=\"text\" id=\"wpforms-7736-field_10\" class=\"wpforms-field-large\" name=\"wpforms[fields][10]\" ><\/div><div id=\"wpforms-7736-field_49-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"49\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_9\">I would like to receive the container\/container at the time below:<\/label><input type=\"text\" id=\"wpforms-7736-field_9\" class=\"wpforms-field-large\" name=\"wpforms[fields][9]\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_11\">Delivery location:<\/label><input type=\"text\" id=\"wpforms-7736-field_11\" class=\"wpforms-field-large\" name=\"wpforms[fields][11]\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_41-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"41\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_34-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"34\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_34\">1. What type of container do you need ?<\/label><select id=\"wpforms-7736-field_34\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][34]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Office container\"  class=\"choice-1 depth-1\"  >Office container<\/option><option value=\"Storage container\"  class=\"choice-2 depth-1\"  >Storage container<\/option><option value=\"Cold storage container\"  class=\"choice-3 depth-1\"  >Cold storage container<\/option><option value=\"Multifunctional container\"  class=\"choice-4 depth-1\"  >Multifunctional container<\/option><option value=\"Living container\"  class=\"choice-5 depth-1\"  >Living container<\/option><option value=\"Container hous\"  class=\"choice-6 depth-1\"  >Container hous<\/option><option value=\"Sanitary container\"  class=\"choice-7 depth-1\"  >Sanitary container<\/option><option value=\"Dressing container\"  class=\"choice-8 depth-1\"  >Dressing container<\/option><option value=\"Other container\"  class=\"choice-9 depth-1\"  >Other container<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_35-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"35\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_35\">1. What container size do you need?<\/label><select id=\"wpforms-7736-field_35\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][35]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Select size\"  class=\"choice-1 depth-1\"  >Select size<\/option><option value=\"5&#039;   (1400mmX2438mmX2591mm)\"  class=\"choice-6 depth-1\"  >5'   (1400mmX2438mmX2591mm)<\/option><option value=\"8&#039;   (2438mmX2438mmX2591mm)\"  class=\"choice-2 depth-1\"  >8'   (2438mmX2438mmX2591mm)<\/option><option value=\"10&#039;  (2991mmX2438mmX2591mm)\"  class=\"choice-3 depth-1\"  >10'  (2991mmX2438mmX2591mm)<\/option><option value=\"20&#039;  (6058mmX2438mmX2591mm)\"  class=\"choice-4 depth-1\"  >20'  (6058mmX2438mmX2591mm)<\/option><option value=\"40&#039;  (12192mmX2438mmX2896mm)\"  class=\"choice-5 depth-1\"  >40'  (12192mmX2438mmX2896mm)<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_37-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"37\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_37\">1. Quantity <\/label><input type=\"text\" id=\"wpforms-7736-field_37\" class=\"wpforms-field-large\" name=\"wpforms[fields][37]\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_52-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"52\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_44-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"44\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_44\">2. What type of container do you need?<\/label><select id=\"wpforms-7736-field_44\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][44]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Office container\"  class=\"choice-1 depth-1\"  >Office container<\/option><option value=\"Storage container\"  class=\"choice-2 depth-1\"  >Storage container<\/option><option value=\"Cold storage container\"  class=\"choice-3 depth-1\"  >Cold storage container<\/option><option value=\"Multifunctional container\"  class=\"choice-4 depth-1\"  >Multifunctional container<\/option><option value=\"Living container\"  class=\"choice-5 depth-1\"  >Living container<\/option><option value=\"Container hous\"  class=\"choice-6 depth-1\"  >Container hous<\/option><option value=\"Sanitary container\"  class=\"choice-7 depth-1\"  >Sanitary container<\/option><option value=\"Dressing container\"  class=\"choice-8 depth-1\"  >Dressing container<\/option><option value=\"Other container\"  class=\"choice-9 depth-1\"  >Other container<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_45-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"45\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_45\">2. What container size do you need? <\/label><select id=\"wpforms-7736-field_45\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][45]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Select size\"  class=\"choice-1 depth-1\"  >Select size<\/option><option value=\"5&#039;   (1400mmX2438mmX2591mm)\"  class=\"choice-6 depth-1\"  >5'   (1400mmX2438mmX2591mm)<\/option><option value=\"8&#039;   (2438mmX2438mmX2591mm)\"  class=\"choice-2 depth-1\"  >8'   (2438mmX2438mmX2591mm)<\/option><option value=\"10&#039;  (2991mmX2438mmX2591mm)\"  class=\"choice-3 depth-1\"  >10'  (2991mmX2438mmX2591mm)<\/option><option value=\"20&#039;  (6058mmX2438mmX2591mm)\"  class=\"choice-4 depth-1\"  >20'  (6058mmX2438mmX2591mm)<\/option><option value=\"40&#039;  (12192mmX2438mmX2896mm)\"  class=\"choice-5 depth-1\"  >40'  (12192mmX2438mmX2896mm)<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_47-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"47\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_47\">2. Quantity<\/label><input type=\"text\" id=\"wpforms-7736-field_47\" class=\"wpforms-field-large\" name=\"wpforms[fields][47]\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_21-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_21\">Other comments:<\/label><textarea id=\"wpforms-7736-field_21\" class=\"wpforms-field-small\" name=\"wpforms[fields][21]\" ><\/textarea><\/div><div id=\"wpforms-7736-field_17-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_17\">File upload:<\/label><div\n\t\tclass=\"wpforms-uploader \"\n\t\tdata-field-id=\"17\"\n\t\tdata-form-id=\"7736\"\n\t\tdata-input-name=\"wpforms_7736_17\"\n\t\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages,svg,svgz\"\n\t\tdata-max-size=\"6442450944\"\n\t\tdata-max-file-number=\"1\"\n\t\tdata-post-max-size=\"6442450944\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-7736-field_17\"\n\t\tname=\"wpforms_7736_17\" \t\tvalue=\"\">\n<\/div><div id=\"wpforms-7736-field_40-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"40\"><label class=\"wpforms-field-label\">GDPR Agreement <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-7736-field_40\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-7736-field_40_1\" name=\"wpforms[fields][40][]\" value=\"I get acquainted with the Data Protection Policy and I agree with it.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-7736-field_40_1\">I get acquainted with the Data Protection Policy and I agree with it.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-7736-field-hp\" class=\"wpforms-field-label\">Email<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-7736-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"7736\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/7580\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-7736\" class=\"wpforms-submit wpforms-mobile-full\" data-alt-text=\"Sending\" data-submit-text=\"Sending\" aria-live=\"assertive\" value=\"wpforms-submit\">Sending<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-1 tb_5155f7d last\">\n                            <\/div>\n                        <\/div>\n        <\/div>\n            <\/div>\n<!--\/themify_builder_content--><\/div>\n<\/div>\n<!-- \/module template_part -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>\/art. number: K1963\/ Support stand for attaching security cameras and lighting fixtures to the container. It can be easily installed in a container corner with a screw connection. Height: 1.5 m Material: galvanized steel, weather resistant \u00a0 WRITE TO US For the container and accessory prices, please complete this inquiry form!<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"Container camera\/ reflector holder","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-7580","page","type-page","status-publish","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/7580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/comments?post=7580"}],"version-history":[{"count":6,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/7580\/revisions"}],"predecessor-version":[{"id":7589,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/7580\/revisions\/7589"}],"wp:attachment":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/media?parent=7580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}