{"id":759,"date":"2018-06-15T08:35:35","date_gmt":"2018-06-15T08:35:35","guid":{"rendered":"http:\/\/mytrejka.nazwa.pl\/mobilbox\/wynajem-kontenerow\/wynajem-kontenerow-biurowych-copy\/"},"modified":"2025-07-09T13:02:50","modified_gmt":"2025-07-09T13:02:50","slug":"office-containers-for-sale","status":"publish","type":"page","link":"https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/","title":{"rendered":"Office containers for sale"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-759\" data-postid=\"759\" class=\"themify_builder_content themify_builder_content-759 themify_builder tf_clear\">\n                    <div  data-css_id=\"4ce11ea\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_4ce11ea tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_2 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_4bfbe97 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_26a6938   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div class=\"su-list\" style=\"margin-left:0px\"><\/p>\n<ul>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Fix-wall or panel-structure designs<\/li>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Easy, quick installation<\/li>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Variable internal rooms<\/li>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Representative external appearance (painted in any shade of the RAL colour scale)<\/li>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Comfortable internal design (varying internal claddings) &#8211; 5\u2019, 8\u2019, 10\u2019, 16\u2019, 20\u2019, 24\u2019 sizes<\/li>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> <a>Flatpack container assembly instructions<\/a><\/li>\n<\/ul>\n<p><\/div>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_6dbeb1e   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2 class=\\\"left_box_title\\\"><span style=\\\"color: #ed1c24;\\\">Purchase professional office containers from Mobilbox!<\/span><\/h2>\n<div class=\\\"left_box_desc\\\">\n<div class=\\\"left_box_title\\\">\u00a0<\/div>\n<div class=\\\"left_box_desc\\\">Buying a Mobilbox office container is an ideal option in case you need an office that can be flexibly adjusted to changing demands, while is quick and convenient to install. It can be the proper choice wherever it is difficult to obtain a building permit.<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_538776f last\">\n                    <div  class=\"module themify_builder_slider_wrap tf_clearfix module-slider tb_6a69d28  slider-overlay  \" data-lazy=\"1\">\n        <div class=\"themify_builder_slider tf_carousel tf_swiper-container tf_rel tf_overflow\" data-lazy=\"1\"        data-visible=\"1\"\n        data-tab-visible=\"\"\n        data-mob-visible=\"0\"\n        data-scroll=\"1\"\n                            data-auto=\"2000\"\n            data-controller=\"0\"\n                data-pause_hover=\"1\"\n        data-speed=\"normal\"\n        data-wrapvar=\"1\"\n        data-slider_nav=\"0\"\n        data-pager=\"1\"\n        data-effect=\"scroll\"\n        data-height=\"variable\"\n        data-css_url=\"https:\/\/mobilbox.hu\/en\/wp-content\/themes\/themify-ultra\/themify\/themify-builder\/css\/modules\/sliders\/carousel,https:\/\/mobilbox.hu\/en\/wp-content\/themes\/themify-ultra\/themify\/themify-builder\/css\/modules\/sliders\/slider\"\n                    >\n        <div class=\"tf_swiper-wrapper tf_lazy tf_rel tf_w tf_h tf_textc\">\n                         <div class=\"tf_swiper-slide\">            <div class=\"slide-inner-wrap\">\n                                    <div class=\"tf_rel tf_lazy slide-image\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/04\/Mercedesiroda1-1024x768-480x300.jpg\" width=\"480\" height=\"300\" class=\"wp-post-image wp-image-5972\" title=\"Mercedesiroda1\" alt=\"Mercedesiroda1\">                                            <\/div>\n                \n                            <\/div>\n        <\/div>                     <div class=\"tf_swiper-slide\" style=\"content-visibility:hidden\">            <div class=\"slide-inner-wrap\">\n                                    <div class=\"tf_rel tf_lazy slide-image\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/irodakontener-belso-1024x768-480x300.jpg\" width=\"480\" height=\"300\" class=\"wp-post-image wp-image-6671\" title=\"irodakontener-belso\" alt=\"irodakontener-belso\">                                            <\/div>\n                \n                            <\/div>\n        <\/div>                     <div class=\"tf_swiper-slide\" style=\"content-visibility:hidden\">            <div class=\"slide-inner-wrap\">\n                                    <div class=\"tf_rel tf_lazy slide-image\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/kont\u00e9nerbels\u01513-1024x768-480x300.jpg\" width=\"480\" height=\"300\" class=\"wp-post-image wp-image-6664\" title=\"kont\u00e9nerbels\u01513\" alt=\"kont\u00e9nerbels\u01513\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/kont\u00e9nerbels\u01513-1024x768-480x300.jpg 480w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/kont\u00e9nerbels\u01513-1024x768-4x3.jpg 4w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>                                            <\/div>\n                \n                            <\/div>\n        <\/div>                     <div class=\"tf_swiper-slide\" style=\"content-visibility:hidden\">            <div class=\"slide-inner-wrap\">\n                                    <div class=\"tf_rel tf_lazy slide-image\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/irodakontener-lepcso-768x1024-480x300.jpg\" width=\"480\" height=\"300\" class=\"wp-post-image wp-image-6668\" title=\"irodakontener-lepcso\" alt=\"irodakontener-lepcso\">                                            <\/div>\n                \n                            <\/div>\n        <\/div>                     <div class=\"tf_swiper-slide\" style=\"content-visibility:hidden\">            <div class=\"slide-inner-wrap\">\n                                    <div class=\"tf_rel tf_lazy slide-image\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/irodakontener-belso2-1024x768-480x300.jpg\" width=\"480\" height=\"300\" class=\"wp-post-image wp-image-6669\" title=\"irodakontener-belso2\" alt=\"irodakontener-belso2\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/irodakontener-belso2-1024x768-480x300.jpg 480w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/05\/irodakontener-belso2-1024x768-4x3.jpg 4w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>                                            <\/div>\n                \n                            <\/div>\n        <\/div>            <\/div>\n    <\/div>\n<\/div>\n        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_fbd6b9f tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_e8340dd first\">\n                            <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"358d20f\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_358d20f tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_2 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_0d297ae first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_db39db7   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2 class=\\\"left_box_title\\\"><span style=\\\"color: #ed1c24;\\\">Who is recommended to buy an office container?<\/span><\/h2>\n<div class=\"su-list\" style=\"margin-left:0px\"><\/p>\n<div class=\\\"left_box_desc\\\">\n<div class=\\\"left_box_title\\\">\u00a0<\/div>\n<div class=\\\"left_box_desc\\\">\n<ul>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Who needs a mobile office or insulated warehouse<\/li>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Who wants simple and quick installation<\/li>\n<li><i class=\"sui sui-star\" style=\"color:#333\"><\/i> Who would like to have a flexibly changeable office with modular expansion options<\/li>\n<\/ul>\n<\/div>\n<p><\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_95eed08 last\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_20a62ab   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2 class=\\\"left_box_title\\\"><span style=\\\"color: #ed1c24;\\\">Why is it Mobilbox to turn to when purchasing an office container?<\/span><\/h2>\n<p>\u00a0<\/p>\n<div class=\\\"left_box_desc\\\">\n<div class=\"su-list\" style=\"margin-left:0px\"><\/div>\n<div class=\\\"left_box_desc\\\">\n<ul>\n<li>Quick quotation<\/li>\n<li>Flexible adjustment to customer demands<\/li>\n<li>Customised payment schemes<\/li>\n<li>Extra insulation when required<\/li>\n<\/ul>\n<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"1ad4e54\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_1ad4e54 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2581db5 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_a88f973   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2><span style=\\\"color: #ed1c24;\\\">Office containers for saletype-specific properties and sizes<\/span><\/h2>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"5656cee\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_5656cee tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_24fa7f4 first\">\n                            <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"6434ea5\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_6434ea5 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_a2b4f49 first\">\n                    <!-- module tab -->\n<div  id=\"tb_04b3311\" class=\"module ui module-tab tb_04b3311 vertical  tb_default_color \" data-lazy=\"1\">\n        <div class=\"tab-nav-current-active tf_hide\">\n\t\t<span class=\"tab_burger_icon_wrap\">\n\t        <span class=\"tab_burger_icon tf_rel\"><\/span>\n\t\t<\/span>\n        <span class=\"tb_activetab_title\">\n            <span class=\"tb_tab_title\">MB20<\/span>\n                    <\/span>\n    <\/div>\n    <ul class=\"tab-nav tf_clearfix tf_scrollbar\">\n                <li class=\"current\" aria-expanded=\"true\">\n            <a href=\"#tab-tb_04b3311-0\">\n                                <span class=\"tb_tab_title\">MB20<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-1\">\n                                <span class=\"tb_tab_title\">MB20H<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-2\">\n                                <span class=\"tb_tab_title\">MB10<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-3\">\n                                <span class=\"tb_tab_title\">MB10H<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-4\">\n                                <span class=\"tb_tab_title\">MB25<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-5\">\n                                <span class=\"tb_tab_title\">MB26<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-6\">\n                                <span class=\"tb_tab_title\">MB08<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-7\">\n                                <span class=\"tb_tab_title\">MB05<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-8\">\n                                <span class=\"tb_tab_title\">MB05 ECO<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-9\">\n                                <span class=\"tb_tab_title\">MB16<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-10\">\n                                <span class=\"tb_tab_title\">MB24<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-11\">\n                                <span class=\"tb_tab_title\">MB30<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-12\">\n                                <span class=\"tb_tab_title\">MB15<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-13\">\n                                <span class=\"tb_tab_title\">MB40<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-14\">\n                                <span class=\"tb_tab_title\">MB27<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-15\">\n                                <span class=\"tb_tab_title\">MB20S<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-16\">\n                                <span class=\"tb_tab_title\">MB05S<\/span>                                            <\/a>\n        <\/li>\n                <li aria-expanded=\"false\">\n            <a href=\"#tab-tb_04b3311-17\">\n                                <span class=\"tb_tab_title\">MB10S<\/span>                                            <\/a>\n        <\/li>\n            <\/ul>\n            <div data-id=\"tab-tb_04b3311-0\" class=\"tab-content tf_clear\" aria-hidden=\"false\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_tiik857\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_z1sm857 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_fwft857   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-1' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb20-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb20-2\/'><img decoding=\"async\" width=\"482\" height=\"358\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-2.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-2-350x260.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-2-300x223.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Design:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Insulation:<\/strong><\/span><\/p>\n<ul>\n<li>Floor: 6\/100 mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Electrical facilities: <\/strong><\/span><\/p>\n<ul>\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>2 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>\u00a0230 V plugs<\/li>\n<li>1 pc 2kW\u00a0 electric heating<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Upon special orders:<\/strong><\/span><\/p>\n<ul>\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-1\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_ds4g857\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_03yg857 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_lipl857   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-2' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb20eco-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb20eco-2\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-2.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-2-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20eco-2-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul>\n<li>Easy to locate and mobilize<\/li>\n<li>Walls: Fix-walled with PU panels<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Drainage in the quoin posts<\/li>\n<li>Walls:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 880 x 2.050 mm<\/li>\n<li>2 pcs white PVC windows: 885 x 1.372 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul>\n<li>Floor: 100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60 mm \u2013 mineral wool<\/li>\n<li>Roof: 100 mm mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul>\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>2 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>2 pcs 230 V\u00a0 plugs<\/li>\n<li>1 pc 2 kW electric heating<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul>\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-2\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_n7t8858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_emq2858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_ruik858   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-3' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb10-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb10-2\/'><img decoding=\"async\" width=\"463\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-2.jpg 463w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-2-350x274.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10-2-300x235.jpg 300w\" sizes=\"(max-width: 463px) 100vw, 463px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul>\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>1 pc white PVC window: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul>\n<li>Floor: 60 mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Electrical facilities: <\/span><\/strong><\/p>\n<ul>\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 2 x 36 Watt fluorescent lamp<\/li>\n<li>\u00a0230 V plugs<\/li>\n<li>1 pc 2 kW electric heating<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul>\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-3\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_2sjq858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_68iz858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_ssha858   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-4' class='gallery galleryid-759 gallery-columns-2 gallery-size-ful'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb10eco-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-1.jpg\" class=\"attachment-ful size-ful\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb10eco-2\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-2.jpg\" class=\"attachment-ful size-ful\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-2.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-2-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb10eco-2-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul>\n<li>Easy to locate and mobilize<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Drainage in the quoin posts<\/li>\n<li>Walls:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 880 x 2.050 mm<\/li>\n<li>1 pc white PVC window: 885 x 1.372 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul>\n<li>Floor: 100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60 mm \u2013 mineral wool<\/li>\n<li>Roof: 100 mm mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul>\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 2 x 36 Watt fluorescent lamp<\/li>\n<li>1 pc 230 V plugs<\/li>\n<li>1 pc 2 kW electric heating<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul>\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-4\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_e6z4858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_doq9858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_cm4u858   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-5' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb25-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb25-3\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-3.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-3-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb25-3-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Office\/sanitary combined functions: practical, full-comfort container<\/li>\n<li>Built-in sanitary unit<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>2 pcs internal doors: 875 x 2.000 mm, 625 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>1\u00a0pc white PVC tilt window: 674 x 574 mm, with thermal insulated frosted glass, without roller blinds<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Sanitary unit facilities\/equipment:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1\u00a0pc ceramic wash basin with a cold water tap, mirror, PVC-shelf, towel-rail, soap-dish<\/li>\n<li>1 pc ceramic flush toilet, with\u00a0toilet tank, toilet roll holder<\/li>\n<li>1 pc clothes rack<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>3 pcs light switches<\/li>\n<li>2 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>2 pcs 1 x 36 Watt fluorescent lamps<\/li>\n<li>3 pcs 230 V plugs<\/li>\n<li>1 pc 0.5 kW electric heater<\/li>\n<li>1 pc 2 kW electric heater<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-5\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_vi6o858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_pw0w858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_bytw858   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-6' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb26-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb26-3\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-3.-e1529572883319.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-3.-e1529572883319.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-3.-e1529572883319-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb26-3.-e1529572883319-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<div class=\"\\&quot;tv_desc\\&quot;\">\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Office\/sanitary combined functions: practical, full-comfort container<\/li>\n<li>Built-in sanitary unit<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>2 pcs internal doors: 875 x 2.000 mm, 625 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>1\u00a0pc white PVC tilt window: 674 x 574 mm, with thermal insulated frosted glass, without roller blinds<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Sanitary unit facilities\/equipment:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1\u00a0pc ceramic wash basin with a cold and hot water tap, mirror, PVC-shelf, towel-rail, soap-dish<\/li>\n<li>1 pc ceramic flush toilet, with\u00a0toilet tank, toilet roll holder<\/li>\n<li>1\u00a0pc acryl shower cabin with a cold and hot mixer tap, shower head, shower curtain<\/li>\n<li>1 pc clothes rack<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Electrical facilities: <\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>3 pcs light switches<\/li>\n<li>2 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>2 pcs 1 x 36 Watt fluorescent lamps<\/li>\n<li>3 pcs 230 V plugs<\/li>\n<li>1 pc 0.5 kW electric heater<\/li>\n<li>1 pc 2 kW electric heater<\/li>\n<li>1 pc 80-liter boiler<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>\n<\/div>\n<div align=\"\\&quot;left\\&quot;\"><a class=\"\\&quot;galerialink\\&quot;\">Image gallery <img decoding=\"async\" src=\"\\&quot;https:\/\/mobilbox.hu\/en\/images\/web\/kepgaleria_link_arrow.png\\&quot;\"><\/a><\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-6\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_2xxr858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_mus4858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_1nbl858   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div class=\"\\&quot;tv_desc\\&quot;\">\n<div id='gallery-7' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb08-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb08-2jpg\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-2jpg.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-2jpg.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-2jpg-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb08-2jpg-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 1 x 36 Watt fluorescent lamp<\/li>\n<li>2 pcs 230 V plugs<\/li>\n<li>1 pc 2 kW electric heater<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-7\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_wklx858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_gihd858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_onyz858   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-8' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb05-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb05-2\/'><img decoding=\"async\" width=\"303\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05-2.jpg 303w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05-2-251x300.jpg 251w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>3 pcs white PVC windows: thermal insulated, with roller blinds\n<ul>\n<li>1 pc of 900 x 1200 mm, tilt and turn mechanism,<\/li>\n<li>1 pc of 900&#215;1200 mm, fixed installation,<\/li>\n<li>1 pc of 900 x 1200 mm, slide window.<\/li>\n<\/ul>\n<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof: 80\/100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 1 x 36 Watt fluorescent lamp<\/li>\n<li>3 pcs 230 V plugs<\/li>\n<li>1 pc 2 kW electric heater<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-8\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_frlp858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_grjj858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_5as3858   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-9' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb05eco-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb05eco-2\/'><img decoding=\"async\" width=\"276\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-2.jpg 276w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-2-229x300.jpg 229w\" sizes=\"(max-width: 276px) 100vw, 276px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Without forklift pocket<\/li>\n<li>Walls: Fix-walled with PU panels\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: plain steel sheet<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>3 pcs white PVC windows: thermal insulated, with roller blinds\n<ul>\n<li>1 pc of 900 x 1200 mm, tilt and turn mechanism,<\/li>\n<li>1 pc of 900&#215;1200 mm, fixed installation,<\/li>\n<li>1 pc of 900 x 1200 mm, slide window.<\/li>\n<\/ul>\n<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 9002)<\/li>\n<li>walls internal: (light grey RAL 9002)<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60 mm \u2013 EPS<\/li>\n<li>Walls: 50\u00a0mm \u2013 PU<\/li>\n<li>Roof: 60 mm EPS +30mm PU<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 1 x 36 Watt fluorescent lamp<\/li>\n<li>2 pcs 230 V plugs<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-9\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_tg3e858\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_olb8858 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_auf3859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-10' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb16-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb16-2\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-2.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-2-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb16-2-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>2 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>3 pcs 230 V plugs<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-10\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_ywzm859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_lyrq859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_jmll859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-11' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb24-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb24-2\/'><img decoding=\"async\" width=\"482\" height=\"321\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-2.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-2-350x233.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb24-2-300x200.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<div class=\"\\&quot;tv_desc\\&quot;\">\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>2 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>3 pcs 230 V plugs<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-11\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_479w859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_s35w859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_zu5l859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-12' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb30-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-1..jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-1..jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-1.-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-1.-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb30-2\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-2..jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-2..jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-2.-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb30-2.-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<div class=\"\\&quot;tv_desc\\&quot;\">\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>3 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>3 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>3 pcs\u00a0 double 230 V plugs<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-12\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_6zan859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_pjk7859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_nqmj859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-13' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb15-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb15-2\/'><img decoding=\"async\" width=\"482\" height=\"306\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-2.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-2-350x222.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb15-2-300x190.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design: <\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Office\/sanitary combined functions: practical, full-comfort container<\/li>\n<li>Built-in sanitary unit<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc glassed outer door: 875 x 2.000 mm<\/li>\n<li>2 pcs internal doors: 875 x 2.000 mm, 625 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: thermal insulated, with roller blinds\n<ul>\n<li>1 pc of 900 x 1200 mm, tilt and turn mechanism,<\/li>\n<li>1 pc of 900 x 1200 mm, slide window.<\/li>\n<\/ul>\n<\/li>\n<li>1\u00a0pc white PVC tilt window: 674 x 574 mm, with thermal insulated frosted glass, without roller blinds<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Sanitary unit facilities\/equipment: <\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1\u00a0pc ceramic wash basin with a cold water tap, mirror, PVC-shelf, towel-rail, soap-dish<\/li>\n<li>1 pc ceramic flush toilet, with\u00a0toilet tank, toilet roll holder<\/li>\n<li>1 pc clothes rack<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Insulation: <\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Electrical facilities:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>2 pcs light switches<\/li>\n<li>2 pcs 1 x 36 Watt fluorescent lamps<\/li>\n<li>2 pcs 230 V plugs and 2 pcs 230V double plugs<\/li>\n<li>1 pc 0.5 kW electric heater and 1 pc 2kW electric heating<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-13\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_x36p859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_5vvd859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_n4to859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-14' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb40-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-1..jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-1..jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-1.-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-1.-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb40-2\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-2.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-2-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb40-2-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design: <\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Office, kitchen, bathroom, bedroom in one container<\/li>\n<li>40\u2019 HC ISO size with CSC plate \u2013 sea transportable<\/li>\n<li>Robust steel construction, also usable under extreme conditions<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: plain steel sheet<\/li>\n<\/ul>\n<\/li>\n<li>Excellent insulation<\/li>\n<li>Split air conditioner outdoor unit is recessed in wall<\/li>\n<li>Comfortable interior design<\/li>\n<li>1 pc outer door: 820 x 2.040 mm, above its 1 x 60 W outdoor lamp<\/li>\n<li>2 pcs internal doors: 720 x 2.000 mm<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: white (RAL 9010)<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Office area equipment:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc white PVC window: 885 x 1.345 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>1 pc indoor air-conditioner unit<\/li>\n<li>1 pc smoke alarm<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 2 x 36 Watt fluorescent lamp<\/li>\n<li>6 pcs 230 V plugs<\/li>\n<li>1 pc internet connection<\/li>\n<li>1 pc 2.0 kW electric heater<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Corridor area equipment:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1\u00a0pc PVC tilt window: 610 x 610 mm, with thermal insulated, without roller blinds<\/li>\n<li>1 pc 2 x 18 Watt fluorescent lamp<\/li>\n<li>1 pc 230 V plug<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Kitchen area equipment:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc refrigerator (96 litre with a 26 litre freezer)<\/li>\n<li>1 pc kitchen counter with lower kitchen cabinet<\/li>\n<li>1 pc single sink with cold and hot water mixer tap<\/li>\n<li>1 pc 2 x 36 Watt fluorescent lamp<\/li>\n<li>2 pcs 230 V plugs<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Bathroom area equipment:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1\u00a0pc PVC tilt window: 610 x 610 mm, with thermal insulated frosted glass, without roller blinds<\/li>\n<li>1\u00a0pc acryl shower cabin with a cold and hot mixer tap, soap-dish, shower head, shower curtain<\/li>\n<li>1\u00a0pc ceramic wash basin with a cold and hot water tap, mirror, towel-rail<\/li>\n<li>1 pc ceramic flush toilet, with\u00a0toilet tank, toilet roll holder<\/li>\n<li>2 pcs clothes racks<\/li>\n<li>1 pc 80-litre electric water heater<\/li>\n<li>1 pc 80 m3 \/ h capacity exhaust fan<\/li>\n<li>2 pcs light switches<\/li>\n<li>1 pc 2 x 18 Watt fluorescent lamp<\/li>\n<li>1 pc 1 x 18 Watt mirror lighting<\/li>\n<li>3 pcs 230 V plugs<\/li>\n<li>1 pc 0.5 kW electric heater<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Bedroom area equipment: <\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc white PVC window: 885 x 1.345 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>1 pc indoor air-conditioner unit<\/li>\n<li>1 pc smoke alarm<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 2 x 36 Watt fluorescent lamp<\/li>\n<li>5 pcs 230 V plugs<\/li>\n<li>1 pc TV connection<\/li>\n<li>1 pc 2.0 kW electric heater<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Insulation: <\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 70\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Electrical facilities:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\"><br>Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-14\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_ld0b859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_6d5l859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_jc8z859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><img decoding=\"async\" class=\"&quot;alignnone\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2019\/04\/MB27-300x141.png\" alt=\"&quot;&quot;\" width=\"&quot;300&quot;\" height=\"&quot;141&quot;\"><\/p>\n<p><strong><span class=\"&quot;left_box_title&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"&quot;left_box_desc&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Office\/sanitary combined functions: practical, full-comfort container<\/li>\n<li>Built-in sanitary unit<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls:\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 875 x 2.000 mm<\/li>\n<li>4 pcs internal doors:\u00a0 625 x 2.000 mm<\/li>\n<li>1 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>2 pcs white PVC tilt window: 674 x 574 mm, with thermal insulated frosted glass, without roller blinds<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: light wood or white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Sanitary unit facilities\/equipment:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>2 pcs ceramic wash basin with a cold and hot water tap, mirror, PVC-shelf, towel-rail, soap-dish<\/li>\n<li>2 pcs ceramic flush toilet, with toilet tank, toilet roll holder<\/li>\n<li>2 pcs clothes rack<\/li>\n<li>1 pc pissoir<\/li>\n<li>1 pc modesty wall<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60\/100\u00a0mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:\u00a0100 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Electrical facilities: <\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>5 pcs light switches<\/li>\n<li>1 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>4 pcs 1 x 36 Watt fluorescent lamps<\/li>\n<li>2 pcs 230 V plugs, 1 pc 230V double plugs<\/li>\n<li>2 pcs 0.5 kW electric heater<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-15\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_l2ln859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_1nkp859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_x84c859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-15' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb20-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/mb20s-irodakontener\/'><img decoding=\"async\" width=\"382\" height=\"382\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2025\/07\/mb20s-irodakontener.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2025\/07\/mb20s-irodakontener.jpg 382w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2025\/07\/mb20s-irodakontener-300x300.jpg 300w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2025\/07\/mb20s-irodakontener-150x150.jpg 150w\" sizes=\"(max-width: 382px) 100vw, 382px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Design:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Without forklift pocket<\/li>\n<li>Walls:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 900 x 2.000 mm<\/li>\n<li>2 pcs white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal:\u00a0 white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Insulation:<\/strong><\/span><\/p>\n<ul>\n<li>Floor: 60 mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof:80 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Electrical facilities: <\/strong><\/span><\/p>\n<ul>\n<li>\u00a05-pole 3 x 32 A, IP44 external connection according to CEE norms, sunken in the roof frame<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>2 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>3 pcs 230 V double plugs<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Upon special orders:<\/strong><\/span><\/p>\n<ul>\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-16\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_qam0859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_lagb859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_mn83859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-16' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb05eco-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb05eco-2\/'><img decoding=\"async\" width=\"276\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-2.jpg 276w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb05eco-2-229x300.jpg 229w\" sizes=\"(max-width: 276px) 100vw, 276px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Design:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Walls: Fix-walled with PU panels\n<ul>\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 900 x 2.000 mm<\/li>\n<li>3 pcs white PVC windows: thermal insulated, with roller blinds\n<ul>\n<li>1 pc of 900 x 1200 mm, tilt and turn mechanism,<\/li>\n<li>1 pc of 900&#215;1200 mm, fixed installation,<\/li>\n<li>1 pc of 900 x 1200 mm, slide window.<\/li>\n<\/ul>\n<\/li>\n<li>Colours:\n<ul>\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal: white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Insulation:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Floor: 60 mm mineral wool<\/li>\n<li>Walls: 60 mm mineral wool<\/li>\n<li>Roof: 80 mm mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Electrical facilities:<\/strong> <\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>1 pc 400 V \/ 5-pole 3 x 32 A external connection according to CEE norms, sunken in the roof frame, connectable<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pc 1 x 36 Watt fluorescent lamp<\/li>\n<li>3 pcs 230 V plugs<\/li>\n<\/ul>\n<p><strong><span class=\"\\&quot;left_box_title\\&quot;\">Upon special orders:<\/span><\/strong><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n            <div data-id=\"tab-tb_04b3311-17\" class=\"tab-content tf_clear\" aria-hidden=\"true\">\n                    <div  data-lazy=\"1\" class=\"module_subrow themify_builder_sub_row tf_w col_align_top tb_col_count_1 tb_6z1x859\">\n                <div  data-lazy=\"1\" class=\"module_column sub_column tb_ummo859 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_k0v5859   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id='gallery-17' class='gallery galleryid-759 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mobilbox.hu\/en\/container-sales\/office-containers-for-sale\/kontenery-biurowe-projekt-mb20-1\/'><img decoding=\"async\" width=\"482\" height=\"362\" src=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1.jpg 482w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1-350x263.jpg 350w, https:\/\/mobilbox.hu\/en\/wp-content\/uploads\/2018\/06\/kontenery-biurowe-projekt-mb20-1-300x225.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<hr>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><strong>Design:<\/strong><\/span><\/p>\n<ul class=\"\\&quot;left_box_desc\\&quot;\">\n<li>Easy to locate and mobilize<\/li>\n<li>Variable panel structure<\/li>\n<li>Container frame: painted steel construction<\/li>\n<li>Without forklift pocket<\/li>\n<li>Walls:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>external:\u00a0profiled steel sheet<\/li>\n<li>internal: chipboard<\/li>\n<\/ul>\n<\/li>\n<li>1 pc outer door: 900 x 2.000 mm<\/li>\n<li>1 pc white PVC windows: 900 x 1.200 mm, tilt and turn mechanism, thermal insulated, with roller blinds<\/li>\n<li>Colours:<br>\n<ul type=\"\\&quot;circle\\&quot;\">\n<li>container frame: fiery red (RAL 3000)<\/li>\n<li>walls external: light grey (RAL 7035)<\/li>\n<li>walls internal:\u00a0 white<\/li>\n<li>floor: light grey PVC<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Insulation:<\/strong><\/span><\/p>\n<ul>\n<li>Floor: 60 mm \u2013 mineral wool<\/li>\n<li>Walls: 60\u00a0mm \u2013 mineral wool<\/li>\n<li>Roof: 80 mm \u2013 mineral wool<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Electrical facilities: <\/strong><\/span><\/p>\n<ul>\n<li>\u00a05-pole 3 x 32 A, IP44 external connection according to CEE norms, sunken in the roof frame<\/li>\n<li>1 pc fuse-box with RCD and circuit breaker<\/li>\n<li>1 pc light switch<\/li>\n<li>1 pcs 2 x 36 Watt fluorescent lamps<\/li>\n<li>1 pcs 230 V double plugs<\/li>\n<\/ul>\n<p><span class=\"\\&quot;left_box_title\\&quot;\"><br><strong>Upon special orders:<\/strong><\/span><\/p>\n<ul>\n<li>External painting in any RAL color<\/li>\n<li>Customized dimensions and designs<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <\/div>\n                <\/div>\n    <\/div>\n<!-- \/module tab -->\n<!-- module text -->\n<div  class=\"module module-text tb_2e38ac6   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h2><span style=\\\"color: #ed1c24;\\\">Schedule of dimensions<\/span><\/h2>\n<p>\u00a0<\/p>\n<div class=\"supsystic-table-loader spinner\"style=\"background-color:#000000\"><\/div><div id=\"supsystic-table-15_75652\" class=\"supsystic-tables-wrap \" style=\" width:100%; visibility: hidden; \" data-table-width-fixed=\"100%\" data-table-width-mobile=\"100%\" ><table id=\"supsystic-table-15\" class=\"supsystic-table border lightboxImg cell-border\" data-id=\"15\" data-view-id=\"15_75652\" data-title=\"kontenery biurowe-sprzedaz\" data-currency-format=\"$1,000.00\" data-percent-format=\"10.00%\" data-date-format=\"DD.MM.YYYY\" data-time-format=\"HH:mm\" data-features=\"[&quot;after_table_loaded_script&quot;]\" data-search-value=\"\" data-loader-icon-name=\"default\" data-loader-icon-items=\"0\" data-loader-color=\"#000000\" data-processing-bg=\"#ffffff\" data-processing-color=\"#000000\" data-lightbox-img=\"\" data-head-rows-count=\"1\" data-pagination-length=\"50,100,All\" data-auto-index=\"off\" data-searching-settings=\"{&quot;columnSearchPosition&quot;:&quot;bottom&quot;,&quot;minChars&quot;:&quot;0&quot;}\" data-lang=\"default\" data-override=\"{&quot;emptyTable&quot;:&quot;&quot;,&quot;info&quot;:&quot;&quot;,&quot;infoEmpty&quot;:&quot;&quot;,&quot;infoFiltered&quot;:&quot;&quot;,&quot;lengthMenu&quot;:&quot;&quot;,&quot;search&quot;:&quot;&quot;,&quot;zeroRecords&quot;:&quot;&quot;,&quot;exportLabel&quot;:&quot;&quot;,&quot;file&quot;:&quot;default&quot;}\" data-merged=\"[{&quot;row&quot;:0,&quot;col&quot;:0,&quot;rowspan&quot;:2,&quot;colspan&quot;:1},{&quot;row&quot;:0,&quot;col&quot;:1,&quot;rowspan&quot;:1,&quot;colspan&quot;:3},{&quot;row&quot;:0,&quot;col&quot;:4,&quot;rowspan&quot;:1,&quot;colspan&quot;:3},{&quot;row&quot;:0,&quot;col&quot;:7,&quot;rowspan&quot;:2,&quot;colspan&quot;:1}]\" data-responsive-mode=\"0\" data-from-history=\"0\" ><thead><tr><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><\/tr><\/thead><tbody><tr style=\"height:px\" ><td data-cell-id=\"A1\" data-x=\"0\" data-y=\"1\" data-db-index=\"1\" class=\"htMiddle htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"TYPE\" data-order=\"TYPE\" style=\"min-width: 17.1756%;\" data-colspan=\"1\" data-rowspan=\"2\" >TYPE <\/td><td data-cell-id=\"B1\" data-x=\"1\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"External dimensions\" data-order=\"External dimensions\" style=\"min-width: 11.8321%;\" data-colspan=\"3\" data-rowspan=\"1\" >External dimensions <\/td><td data-cell-id=\"C1\" data-x=\"2\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"External dimensions\" data-order=\"External dimensions\" style=\"min-width: 11.8321%;\" data-hide=\"true\" >External dimensions <\/td><td data-cell-id=\"D1\" data-x=\"3\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"External dimensions\" data-order=\"External dimensions\" style=\"min-width: 11.8321%;\" data-hide=\"true\" >External dimensions <\/td><td data-cell-id=\"E1\" data-x=\"4\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"Internal dimensions\" data-order=\"Internal dimensions\" style=\"min-width: 11.8321%;\" data-colspan=\"3\" data-rowspan=\"1\" >Internal dimensions <\/td><td data-cell-id=\"F1\" data-x=\"5\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"Internal dimensions\" data-order=\"Internal dimensions\" style=\"min-width: 11.8321%;\" data-hide=\"true\" >Internal dimensions <\/td><td data-cell-id=\"G1\" data-x=\"6\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"Internal dimensions\" data-order=\"Internal dimensions\" style=\"min-width: 11.8321%;\" data-hide=\"true\" >Internal dimensions <\/td><td data-cell-id=\"H1\" data-x=\"7\" data-y=\"1\" data-db-index=\"1\" class=\"htMiddle htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"Weight\" data-order=\"Weight\" style=\"min-width: 11.8321%;\" data-colspan=\"1\" data-rowspan=\"2\" >Weight <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A2\" data-x=\"0\" data-y=\"2\" data-db-index=\"2\" class=\"htMiddle htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B2\" data-x=\"1\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"L\" data-order=\"L\" >L <\/td><td data-cell-id=\"C2\" data-x=\"2\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"W\" data-order=\"W\" >W <\/td><td data-cell-id=\"D2\" data-x=\"3\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"H\" data-order=\"H\" >H <\/td><td data-cell-id=\"E2\" data-x=\"4\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"L\" data-order=\"L\" >L <\/td><td data-cell-id=\"F2\" data-x=\"5\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"W\" data-order=\"W\" >W <\/td><td data-cell-id=\"G2\" data-x=\"6\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"H\" data-order=\"H\" >H <\/td><td data-cell-id=\"H2\" data-x=\"7\" data-y=\"2\" data-db-index=\"2\" class=\"htMiddle htCenter bg-ed1c23 bold\" data-cell-type=\"text\" data-original-value=\"Weight\" data-order=\"Weight\" data-hide=\"true\" >Weight <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A3\" data-x=\"0\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB20\" data-order=\"MB20\" >MB20 <\/td><td data-cell-id=\"B3\" data-x=\"1\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"6,058\" data-order=\"6,058\" >6,058 <\/td><td data-cell-id=\"C3\" data-x=\"2\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D3\" data-x=\"3\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E3\" data-x=\"4\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"5,858\" data-order=\"5,858\" >5,858 <\/td><td data-cell-id=\"F3\" data-x=\"5\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G3\" data-x=\"6\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H3\" data-x=\"7\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,980\" data-order=\"1,980\" >1,980 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A4\" data-x=\"0\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB20H\" data-order=\"MB20H\" >MB20H <\/td><td data-cell-id=\"B4\" data-x=\"1\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"6,058\" data-order=\"6,058\" >6,058 <\/td><td data-cell-id=\"C4\" data-x=\"2\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D4\" data-x=\"3\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,765\" data-order=\"2,765\" >2,765 <\/td><td data-cell-id=\"E4\" data-x=\"4\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"5,858\" data-order=\"5,858\" >5,858 <\/td><td data-cell-id=\"F4\" data-x=\"5\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G4\" data-x=\"6\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,500\" data-order=\"2,500\" >2,500 <\/td><td data-cell-id=\"H4\" data-x=\"7\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,080\" data-order=\"2,080\" >2,080 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A5\" data-x=\"0\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB20S\" data-order=\"MB20S\" >MB20S <\/td><td data-cell-id=\"B5\" data-x=\"1\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"6,058\" data-order=\"6,058\" >6,058 <\/td><td data-cell-id=\"C5\" data-x=\"2\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D5\" data-x=\"3\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E5\" data-x=\"4\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"5,844\" data-order=\"5,844\" >5,844 <\/td><td data-cell-id=\"F5\" data-x=\"5\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,231\" data-order=\"2,231\" >2,231 <\/td><td data-cell-id=\"G5\" data-x=\"6\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,300\" data-order=\"2,300\" >2,300 <\/td><td data-cell-id=\"H5\" data-x=\"7\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1890\" data-order=\"1890\" >1890 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A6\" data-x=\"0\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB10\" data-order=\"MB10\" >MB10 <\/td><td data-cell-id=\"B6\" data-x=\"1\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,991\" data-order=\"2,991\" >2,991 <\/td><td data-cell-id=\"C6\" data-x=\"2\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D6\" data-x=\"3\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E6\" data-x=\"4\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,791\" data-order=\"2,791\" >2,791 <\/td><td data-cell-id=\"F6\" data-x=\"5\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G6\" data-x=\"6\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H6\" data-x=\"7\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,130\" data-order=\"1,130\" >1,130 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A7\" data-x=\"0\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB10H\" data-order=\"MB10H\" >MB10H <\/td><td data-cell-id=\"B7\" data-x=\"1\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,991\" data-order=\"2,991\" >2,991 <\/td><td data-cell-id=\"C7\" data-x=\"2\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D7\" data-x=\"3\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,765\" data-order=\"2,765\" >2,765 <\/td><td data-cell-id=\"E7\" data-x=\"4\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,791\" data-order=\"2,791\" >2,791 <\/td><td data-cell-id=\"F7\" data-x=\"5\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G7\" data-x=\"6\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,500\" data-order=\"2,500\" >2,500 <\/td><td data-cell-id=\"H7\" data-x=\"7\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" ><\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A8\" data-x=\"0\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB10S\" data-order=\"MB10S\" >MB10S <\/td><td data-cell-id=\"B8\" data-x=\"1\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,991\" data-order=\"2,991\" >2,991 <\/td><td data-cell-id=\"C8\" data-x=\"2\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D8\" data-x=\"3\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E8\" data-x=\"4\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,775\" data-order=\"2,775\" >2,775 <\/td><td data-cell-id=\"F8\" data-x=\"5\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,231\" data-order=\"2,231\" >2,231 <\/td><td data-cell-id=\"G8\" data-x=\"6\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,300\" data-order=\"2,300\" >2,300 <\/td><td data-cell-id=\"H8\" data-x=\"7\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" ><\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A9\" data-x=\"0\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB25\" data-order=\"MB25\" >MB25 <\/td><td data-cell-id=\"B9\" data-x=\"1\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"6,058\" data-order=\"6,058\" >6,058 <\/td><td data-cell-id=\"C9\" data-x=\"2\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D9\" data-x=\"3\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E9\" data-x=\"4\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"5,858\" data-order=\"5,858\" >5,858 <\/td><td data-cell-id=\"F9\" data-x=\"5\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G9\" data-x=\"6\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H9\" data-x=\"7\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,150\" data-order=\"2,150\" >2,150 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A10\" data-x=\"0\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB26\" data-order=\"MB26\" >MB26 <\/td><td data-cell-id=\"B10\" data-x=\"1\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"6,058\" data-order=\"6,058\" >6,058 <\/td><td data-cell-id=\"C10\" data-x=\"2\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D10\" data-x=\"3\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E10\" data-x=\"4\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"5,858\" data-order=\"5,858\" >5,858 <\/td><td data-cell-id=\"F10\" data-x=\"5\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G10\" data-x=\"6\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H10\" data-x=\"7\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,220\" data-order=\"2,220\" >2,220 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A11\" data-x=\"0\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB08\" data-order=\"MB08\" >MB08 <\/td><td data-cell-id=\"B11\" data-x=\"1\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"C11\" data-x=\"2\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D11\" data-x=\"3\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E11\" data-x=\"4\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,235\" data-order=\"2,235\" >2,235 <\/td><td data-cell-id=\"F11\" data-x=\"5\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G11\" data-x=\"6\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H11\" data-x=\"7\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter\" data-cell-type=\"text\" data-cell-format-type=\"number\" data-original-value=\"720\" data-order=\"720\" >720 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A12\" data-x=\"0\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB05\" data-order=\"MB05\" >MB05 <\/td><td data-cell-id=\"B12\" data-x=\"1\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,400\" data-order=\"1,400\" >1,400 <\/td><td data-cell-id=\"C12\" data-x=\"2\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D12\" data-x=\"3\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E12\" data-x=\"4\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,200\" data-order=\"1,200\" >1,200 <\/td><td data-cell-id=\"F12\" data-x=\"5\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G12\" data-x=\"6\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H12\" data-x=\"7\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter\" data-cell-type=\"text\" data-cell-format-type=\"number\" data-original-value=\"620\" data-order=\"620\" >620 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A13\" data-x=\"0\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB05S\" data-order=\"MB05S\" >MB05S <\/td><td data-cell-id=\"B13\" data-x=\"1\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,418\" data-order=\"1,418\" >1,418 <\/td><td data-cell-id=\"C13\" data-x=\"2\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D13\" data-x=\"3\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E13\" data-x=\"4\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,200\" data-order=\"1,200\" >1,200 <\/td><td data-cell-id=\"F13\" data-x=\"5\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G13\" data-x=\"6\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,300\" data-order=\"2,300\" >2,300 <\/td><td data-cell-id=\"H13\" data-x=\"7\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter\" data-cell-type=\"text\" data-cell-format-type=\"number\" data-original-value=\"\" data-order=\"\" ><\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A14\" data-x=\"0\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB05 ECO\" data-order=\"MB05 ECO\" >MB05 ECO <\/td><td data-cell-id=\"B14\" data-x=\"1\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,400\" data-order=\"1,400\" >1,400 <\/td><td data-cell-id=\"C14\" data-x=\"2\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D14\" data-x=\"3\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E14\" data-x=\"4\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,200\" data-order=\"1,200\" >1,200 <\/td><td data-cell-id=\"F14\" data-x=\"5\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,270\" data-order=\"2,270\" >2,270 <\/td><td data-cell-id=\"G14\" data-x=\"6\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H14\" data-x=\"7\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter\" data-cell-type=\"text\" data-cell-format-type=\"number\" data-original-value=\"650\" data-order=\"650\" >650 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A15\" data-x=\"0\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB16\" data-order=\"MB16\" >MB16 <\/td><td data-cell-id=\"B15\" data-x=\"1\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"4,880\" data-order=\"4,880\" >4,880 <\/td><td data-cell-id=\"C15\" data-x=\"2\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D15\" data-x=\"3\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E15\" data-x=\"4\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"4,680\" data-order=\"4,680\" >4,680 <\/td><td data-cell-id=\"F15\" data-x=\"5\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G15\" data-x=\"6\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H15\" data-x=\"7\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,620\" data-order=\"1,620\" >1,620 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A16\" data-x=\"0\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB24\" data-order=\"MB24\" >MB24 <\/td><td data-cell-id=\"B16\" data-x=\"1\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"7,325\" data-order=\"7,325\" >7,325 <\/td><td data-cell-id=\"C16\" data-x=\"2\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D16\" data-x=\"3\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E16\" data-x=\"4\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"7,125\" data-order=\"7,125\" >7,125 <\/td><td data-cell-id=\"F16\" data-x=\"5\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G16\" data-x=\"6\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H16\" data-x=\"7\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,390\" data-order=\"2,390\" >2,390 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A17\" data-x=\"0\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB30\" data-order=\"MB30\" >MB30 <\/td><td data-cell-id=\"B17\" data-x=\"1\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"9,125\" data-order=\"9,125\" >9,125 <\/td><td data-cell-id=\"C17\" data-x=\"2\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D17\" data-x=\"3\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E17\" data-x=\"4\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"8,925\" data-order=\"8,925\" >8,925 <\/td><td data-cell-id=\"F17\" data-x=\"5\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G17\" data-x=\"6\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H17\" data-x=\"7\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,890\" data-order=\"2,890\" >2,890 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A18\" data-x=\"0\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB15\" data-order=\"MB15\" >MB15 <\/td><td data-cell-id=\"B18\" data-x=\"1\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,991\" data-order=\"2,991\" >2,991 <\/td><td data-cell-id=\"C18\" data-x=\"2\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D18\" data-x=\"3\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,591\" data-order=\"2,591\" >2,591 <\/td><td data-cell-id=\"E18\" data-x=\"4\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,791\" data-order=\"2,791\" >2,791 <\/td><td data-cell-id=\"F18\" data-x=\"5\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,238\" data-order=\"2,238\" >2,238 <\/td><td data-cell-id=\"G18\" data-x=\"6\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,330\" data-order=\"2,330\" >2,330 <\/td><td data-cell-id=\"H18\" data-x=\"7\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"1,280\" data-order=\"1,280\" >1,280 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A19\" data-x=\"0\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"MB40\" data-order=\"MB40\" >MB40 <\/td><td data-cell-id=\"B19\" data-x=\"1\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"12,192\" data-order=\"12,192\" >12,192 <\/td><td data-cell-id=\"C19\" data-x=\"2\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,438\" data-order=\"2,438\" >2,438 <\/td><td data-cell-id=\"D19\" data-x=\"3\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,896\" data-order=\"2,896\" >2,896 <\/td><td data-cell-id=\"E19\" data-x=\"4\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"12,052\" data-order=\"12,052\" >12,052 <\/td><td data-cell-id=\"F19\" data-x=\"5\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"12,052\" data-order=\"12,052\" >12,052 <\/td><td data-cell-id=\"G19\" data-x=\"6\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"2,500\" data-order=\"2,500\" >2,500 <\/td><td data-cell-id=\"H19\" data-x=\"7\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter\" data-cell-type=\"text\" data-original-value=\"5,975\" data-order=\"5,975\" >5,975 <\/td><\/tr><\/tbody><\/table><!-- \/#supsystic-table-15.supsystic-table --><\/div><!-- \/.supsystic-tables-wrap --><!-- Tables Generator by Supsystic --><!-- Version:1.14.2 --><!-- http:\/\/supsystic.com\/ -->    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"68a45d7\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_68a45d7 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_a9438e2 first\">\n                    <!-- module template_part -->\n<div  class=\"module module-layout-part tb_33fd9f8 \">\n    <div class=\"tb_layout_part_wrap tf_w\"><!--themify_builder_content-->\n    <div  class=\"themify_builder_content themify_builder_content-3434 themify_builder not_editable_builder in_the_loop\" data-postid=\"3434\">\n                        <div  data-css_id=\"7885e66\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_7885e66 tf_w\">\n            <span  class=\"builder_row_cover tf_abs\" data-lazy=\"1\"><\/span>            <div class=\"row_inner col_align_top tb_col_count_3 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col4-1 tb_a5f2af4 first\">\n                            <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_6f6ac2e\">\n                    <!-- module fancy heading -->\n<div  class=\"module module-fancy-heading tb_cfaf205 \" data-lazy=\"1\">\n        <h2 class=\"fancy-heading tf_textc\">\n    <span class=\"main-head tf_block\">\n                    WRITE TO US            <\/span>\n\n    \n    <span class=\"sub-head tf_block tf_rel\">\n                                <\/span>\n    <\/h2>\n<\/div>\n<!-- \/module fancy heading -->\n<!-- module text -->\n<div  class=\"module module-text tb_8d9d061  repeat \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p style=\"text-align: center;\">For the container and accessory prices, please complete this inquiry form!<\/p>\n<p style=\"text-align: center;\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-7736\"><form id=\"wpforms-form-7736\" class=\"wpforms-validate wpforms-form\" data-formid=\"7736\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/759?wpforms_form_id=7736\" data-token=\"f18296b1c5cca6684f6c5d7cf562b73a\" data-token-time=\"1788322399\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-7736-field_53-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-type=\"hidden\" data-field-id=\"53\"><input type=\"hidden\" id=\"wpforms-7736-field_53\" name=\"wpforms[fields][53]\" value=\"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/759\"><\/div><div id=\"wpforms-7736-field_50-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"50\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_2\">Company name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-7736-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-7736-field_28-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_28\">Phone: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-7736-field_28\" class=\"wpforms-field-large wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][28]\" aria-label=\"Phone:\" required><\/div><div id=\"wpforms-7736-field_51-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"51\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_51\">Contact person name:<\/label><input type=\"text\" id=\"wpforms-7736-field_51\" class=\"wpforms-field-medium\" name=\"wpforms[fields][51]\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_19-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_19\">Postal code, city:<\/label><input type=\"text\" id=\"wpforms-7736-field_19\" class=\"wpforms-field-large\" name=\"wpforms[fields][19]\" ><\/div><div id=\"wpforms-7736-field_20-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_20\">Email:<\/label><input type=\"email\" id=\"wpforms-7736-field_20\" class=\"wpforms-field-large\" name=\"wpforms[fields][20]\" spellcheck=\"false\" ><\/div><div id=\"wpforms-7736-field_24-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_24\">Rental\/buy:<\/label><select id=\"wpforms-7736-field_24\" class=\"wpforms-field-large\" name=\"wpforms[fields][24]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Rental\/Buy<\/option><option value=\"I would like to rent\"  class=\"choice-1 depth-1\"  >I would like to rent<\/option><option value=\"I would like to buy\"  class=\"choice-2 depth-1\"  >I would like to buy<\/option><\/select><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_10-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"10\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_10\">Expected time period of rental:<\/label><input type=\"text\" id=\"wpforms-7736-field_10\" class=\"wpforms-field-large\" name=\"wpforms[fields][10]\" ><\/div><div id=\"wpforms-7736-field_49-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"49\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_9\">I would like to receive the container\/container at the time below:<\/label><input type=\"text\" id=\"wpforms-7736-field_9\" class=\"wpforms-field-large\" name=\"wpforms[fields][9]\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-7736-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_11\">Delivery location:<\/label><input type=\"text\" id=\"wpforms-7736-field_11\" class=\"wpforms-field-large\" name=\"wpforms[fields][11]\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_41-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"41\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_34-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"34\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_34\">1. What type of container do you need ?<\/label><select id=\"wpforms-7736-field_34\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][34]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Office container\"  class=\"choice-1 depth-1\"  >Office container<\/option><option value=\"Storage container\"  class=\"choice-2 depth-1\"  >Storage container<\/option><option value=\"Cold storage container\"  class=\"choice-3 depth-1\"  >Cold storage container<\/option><option value=\"Multifunctional container\"  class=\"choice-4 depth-1\"  >Multifunctional container<\/option><option value=\"Living container\"  class=\"choice-5 depth-1\"  >Living container<\/option><option value=\"Container hous\"  class=\"choice-6 depth-1\"  >Container hous<\/option><option value=\"Sanitary container\"  class=\"choice-7 depth-1\"  >Sanitary container<\/option><option value=\"Dressing container\"  class=\"choice-8 depth-1\"  >Dressing container<\/option><option value=\"Other container\"  class=\"choice-9 depth-1\"  >Other container<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_35-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"35\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_35\">1. What container size do you need?<\/label><select id=\"wpforms-7736-field_35\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][35]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Select size\"  class=\"choice-1 depth-1\"  >Select size<\/option><option value=\"5&#039;   (1400mmX2438mmX2591mm)\"  class=\"choice-6 depth-1\"  >5'   (1400mmX2438mmX2591mm)<\/option><option value=\"8&#039;   (2438mmX2438mmX2591mm)\"  class=\"choice-2 depth-1\"  >8'   (2438mmX2438mmX2591mm)<\/option><option value=\"10&#039;  (2991mmX2438mmX2591mm)\"  class=\"choice-3 depth-1\"  >10'  (2991mmX2438mmX2591mm)<\/option><option value=\"20&#039;  (6058mmX2438mmX2591mm)\"  class=\"choice-4 depth-1\"  >20'  (6058mmX2438mmX2591mm)<\/option><option value=\"40&#039;  (12192mmX2438mmX2896mm)\"  class=\"choice-5 depth-1\"  >40'  (12192mmX2438mmX2896mm)<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_37-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"37\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_37\">1. Quantity <\/label><input type=\"text\" id=\"wpforms-7736-field_37\" class=\"wpforms-field-large\" name=\"wpforms[fields][37]\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_52-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"52\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_44-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"44\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_44\">2. What type of container do you need?<\/label><select id=\"wpforms-7736-field_44\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"1\" name=\"wpforms[fields][44]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Office container\"  class=\"choice-1 depth-1\"  >Office container<\/option><option value=\"Storage container\"  class=\"choice-2 depth-1\"  >Storage container<\/option><option value=\"Cold storage container\"  class=\"choice-3 depth-1\"  >Cold storage container<\/option><option value=\"Multifunctional container\"  class=\"choice-4 depth-1\"  >Multifunctional container<\/option><option value=\"Living container\"  class=\"choice-5 depth-1\"  >Living container<\/option><option value=\"Container hous\"  class=\"choice-6 depth-1\"  >Container hous<\/option><option value=\"Sanitary container\"  class=\"choice-7 depth-1\"  >Sanitary container<\/option><option value=\"Dressing container\"  class=\"choice-8 depth-1\"  >Dressing container<\/option><option value=\"Other container\"  class=\"choice-9 depth-1\"  >Other container<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_45-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-type=\"select\" data-field-id=\"45\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_45\">2. What container size do you need? <\/label><select id=\"wpforms-7736-field_45\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][45]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'><\/option><option value=\"Select size\"  class=\"choice-1 depth-1\"  >Select size<\/option><option value=\"5&#039;   (1400mmX2438mmX2591mm)\"  class=\"choice-6 depth-1\"  >5'   (1400mmX2438mmX2591mm)<\/option><option value=\"8&#039;   (2438mmX2438mmX2591mm)\"  class=\"choice-2 depth-1\"  >8'   (2438mmX2438mmX2591mm)<\/option><option value=\"10&#039;  (2991mmX2438mmX2591mm)\"  class=\"choice-3 depth-1\"  >10'  (2991mmX2438mmX2591mm)<\/option><option value=\"20&#039;  (6058mmX2438mmX2591mm)\"  class=\"choice-4 depth-1\"  >20'  (6058mmX2438mmX2591mm)<\/option><option value=\"40&#039;  (12192mmX2438mmX2896mm)\"  class=\"choice-5 depth-1\"  >40'  (12192mmX2438mmX2896mm)<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-7736-field_47-container\" class=\"wpforms-field wpforms-field-text\" data-field-type=\"text\" data-field-id=\"47\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_47\">2. Quantity<\/label><input type=\"text\" id=\"wpforms-7736-field_47\" class=\"wpforms-field-large\" name=\"wpforms[fields][47]\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-7736-field_21-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_21\">Other comments:<\/label><textarea id=\"wpforms-7736-field_21\" class=\"wpforms-field-small\" name=\"wpforms[fields][21]\" ><\/textarea><\/div><div id=\"wpforms-7736-field_17-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-7736-field_17\">File upload:<\/label><div\n\t\tclass=\"wpforms-uploader \"\n\t\tdata-field-id=\"17\"\n\t\tdata-form-id=\"7736\"\n\t\tdata-input-name=\"wpforms_7736_17\"\n\t\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages,svg,svgz\"\n\t\tdata-max-size=\"6442450944\"\n\t\tdata-max-file-number=\"1\"\n\t\tdata-post-max-size=\"6442450944\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-7736-field_17\"\n\t\tname=\"wpforms_7736_17\" \t\tvalue=\"\">\n<\/div><div id=\"wpforms-7736-field_40-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-type=\"gdpr-checkbox\" data-field-id=\"40\"><label class=\"wpforms-field-label\">GDPR Agreement <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-7736-field_40\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-7736-field_40_1\" name=\"wpforms[fields][40][]\" value=\"I get acquainted with the Data Protection Policy and I agree with it.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-7736-field_40_1\">I get acquainted with the Data Protection Policy and I agree with it.<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-7736-field-hp\" class=\"wpforms-field-label\">Name<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-7736-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"7736\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/759\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-7736\" class=\"wpforms-submit wpforms-mobile-full\" data-alt-text=\"Sending\" data-submit-text=\"Sending\" aria-live=\"assertive\" value=\"wpforms-submit\">Sending<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-1 tb_5155f7d last\">\n                            <\/div>\n                        <\/div>\n        <\/div>\n            <\/div>\n<!--\/themify_builder_content--><\/div>\n<\/div>\n<!-- \/module template_part -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-css_id=\"5a9dc81\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_5a9dc81 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_9551d05 first\">\n                    <!-- module template_part -->\n<div  class=\"module module-layout-part tb_3476f58 \">\n    <div class=\"tb_layout_part_wrap tf_w\"><!--themify_builder_content-->\n    <div  class=\"themify_builder_content themify_builder_content-2747 themify_builder not_editable_builder in_the_loop\" data-postid=\"2747\">\n                        <div  data-css_id=\"b242e5c\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_b242e5c tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_2 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_94876dd first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_f36547a  repeat \" data-lazy=\"1\">\n    <h3 class=\"module-title\">Our services<\/h3>    <div  class=\"tb_text_wrap\">\n        <div class=\"su-list\" style=\"margin-left:0px\"><\/p><ul><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container rental<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container sales<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container leasing<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> consultancy<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container design<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container manufacturing<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container installation (craning, assembly)<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container transportation<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> container maintenance<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> satisfaction of special demands<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> sales of container parts<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> seal salessprzeda\u017c plomb<\/li><\/ul><p><\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_9f0e4ff last\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_f0c2ef3  repeat \" data-lazy=\"1\">\n    <h3 class=\"module-title\">Field of the application of our office containers<\/h3>    <div  class=\"tb_text_wrap\">\n        <div class=\"su-list\" style=\"margin-left:0px\"><\/p><ul><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> project office<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> managerial office<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> changing room<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> smoking room<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> accommodation<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> warm shelter<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> workshop<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> reception, guarding post<\/li><li><i class=\"sui sui-check-square-o\" style=\"color:#ed1c24\"><\/i> point of sales, selling space<\/li><\/ul><p><\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n            <\/div>\n<!--\/themify_builder_content--><\/div>\n<\/div>\n<!-- \/module template_part -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>Purchase professional office containers from Mobilbox! \u00a0 Buying a Mobilbox office container is an ideal option in case you need an office that can be flexibly adjusted to changing demands, while is quick and convenient to install. It can be the proper choice wherever it is difficult to obtain a building permit. Who is recommended [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":14,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-759","page","type-page","status-publish","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"_links":{"self":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/comments?post=759"}],"version-history":[{"count":26,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/759\/revisions"}],"predecessor-version":[{"id":8118,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/759\/revisions\/8118"}],"up":[{"embeddable":true,"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/pages\/14"}],"wp:attachment":[{"href":"https:\/\/mobilbox.hu\/en\/wp-json\/wp\/v2\/media?parent=759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}